{"id":5103,"date":"2022-03-15T15:49:54","date_gmt":"2022-03-15T15:49:54","guid":{"rendered":"https:\/\/wptf.themepul.co\/restly\/?page_id=5103"},"modified":"2023-01-18T03:36:19","modified_gmt":"2023-01-18T03:36:19","slug":"pricing","status":"publish","type":"page","link":"https:\/\/foresight-lab.com\/en\/pricing\/","title":{"rendered":"Pricing"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5103\" class=\"elementor elementor-5103\">\r\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d148a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d148a0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fa87a4\" data-id=\"4fa87a4\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c69ebde elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c69ebde\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2baeb94\" data-id=\"2baeb94\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3dbc45 elementor-widget elementor-widget-restly_title\" data-id=\"c3dbc45\" data-element_type=\"widget\" data-widget_type=\"restly_title.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t        <div class=\"restly-section-title-wrapper\">\r\n            <div class=\"restly-section-title\">\r\n                <h6 class=\"restly-section-stitle\"><span>Pricing Packages<\/span><\/h6>                <h2 class=\"restly-section-title\">Choose the Right Plan For You<\/h2>\r\n            <\/div>\r\n        <\/div>\r\n        \t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-64e7391 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64e7391\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-10347f6\" data-id=\"10347f6\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cb594f elementor-widget elementor-widget-restly_pricing_tab2\" data-id=\"0cb594f\" data-element_type=\"widget\" data-widget_type=\"restly_pricing_tab2.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\r\n\t\t\t<script>\r\n\t\t\tjQuery(document).ready(function($) {\r\n\t\t\t\t\"use strict\";\r\n\t\t\t\tif ($(\".pricing-tab\").length) {\r\n                    $(\".pricing-tab button:first-child\").click(function () {\r\n                        $(this).parent(\".pricing-tab\").addClass(\"for-yearly\");\r\n                    });\r\n                    $(\".pricing-tab button:last-child\").click(function () {\r\n                        $(this).parent(\".pricing-tab\").removeClass(\"for-yearly\");\r\n                    });\r\n                }\r\n\t\t\t});\r\n\t\t\t<\/script>        <div class=\"restly-pricing-tabs-wrapper pricing-tab-v2-wrapper\">\r\n            <div class=\"pricing-top-area\">\r\n                <div class=\"pricing-tab nav nav-pills\" id=\"v-pills-tab-540\" role=\"tablist\" aria-orientation=\"vertical\">\r\n                                        <button class=\"nav-link active\" id=\"pricing-1-tab2\" data-bs-toggle=\"pill\" data-bs-target=\"#pricing-item2-1\" type=\"button\" role=\"tab\" aria-controls=\"pricing-item2-1\" aria-selected=\"true\">Monthly<\/button>\r\n                                        <button class=\"nav-link \" id=\"pricing-2-tab2\" data-bs-toggle=\"pill\" data-bs-target=\"#pricing-item2-2\" type=\"button\" role=\"tab\" aria-controls=\"pricing-item2-2\" aria-selected=\"true\">Custom<\/button>\r\n                                    <\/div>\r\n                \r\n            <\/div>\r\n            <div class=\"tab-content pricing-content-areas\" id=\"v-pills-tabContent-540\">\r\n                            <div class=\"tab-pane fade show show active\" id=\"pricing-item2-1\" role=\"tabpanel\" aria-labelledby=\"pricing-1-tab2\">\r\n                \t\t<div data-elementor-type=\"section\" data-elementor-id=\"4948\" class=\"elementor elementor-4948\">\r\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7346fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7346fe\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5646b8f\" data-id=\"5646b8f\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f144159 elementor-widget elementor-widget-restly_pricing_v3\" data-id=\"f144159\" data-element_type=\"widget\" data-widget_type=\"restly_pricing_v3.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t        <div class=\"restly-pricing-v3-wrapper\">\r\n            <div class=\"pricing-item-seven\">\r\n                <div class=\"pricing-top\">\r\n                    <div class=\"price-top-left\">\r\n                        <h4 class=\"pricing-title\">STAND ALONE SERVER<\/h4>\r\n                        <span><\/span>\r\n                    <\/div>\r\n                    <span class=\"price\"><\/span>\r\n                <\/div>\r\n                <ul class=\"list-style-three\">\r\n                                        <li class=\"elementor-repeater-item-55cbcba\"><i class=\"bi bi-check-circle\"><\/i>Free Server Deployment<\/li>\r\n                                        <li class=\"elementor-repeater-item-6b6851f\"><i class=\"bi bi-check-circle\"><\/i>Unlimited Apps &amp; Schedules<\/li>\r\n                                        <li class=\"elementor-repeater-item-84a187c\"><i class=\"bi bi-check-circle\"><\/i>Free Six Months Support<\/li>\r\n                                    <\/ul>\r\n                <a class=\"theme-btn style-six\" href=\"\/contact-us\" target=\"_blank\" rel=\"nofollow\">Contact Us<i class=\"\"><\/i><\/a>            <\/div>\r\n        <\/div>\r\n        \t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-adda7b4\" data-id=\"adda7b4\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d7316f elementor-widget elementor-widget-restly_pricing_v3\" data-id=\"3d7316f\" data-element_type=\"widget\" data-widget_type=\"restly_pricing_v3.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t        <div class=\"restly-pricing-v3-wrapper\">\r\n            <div class=\"pricing-item-seven\">\r\n                <div class=\"pricing-top\">\r\n                    <div class=\"price-top-left\">\r\n                        <h4 class=\"pricing-title\">CLOUD SERVICES<\/h4>\r\n                        <span><\/span>\r\n                    <\/div>\r\n                    <span class=\"price\"><\/span>\r\n                <\/div>\r\n                <ul class=\"list-style-three\">\r\n                                        <li class=\"elementor-repeater-item-55cbcba\"><i class=\"bi bi-check-circle\"><\/i>No Servers Required<\/li>\r\n                                        <li class=\"elementor-repeater-item-6b6851f\"><i class=\"bi bi-check-circle\"><\/i>Limited Apps &amp; Schedules<\/li>\r\n                                        <li class=\"elementor-repeater-item-84a187c\"><i class=\"bi bi-check-circle\"><\/i>Free Online Support<\/li>\r\n                                    <\/ul>\r\n                <a class=\"theme-btn style-six\" href=\"\/contact-us\" target=\"_blank\" rel=\"nofollow\">Contact Us<i class=\"\"><\/i><\/a>            <\/div>\r\n        <\/div>\r\n        \t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ecf4ae1\" data-id=\"ecf4ae1\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75627c9 elementor-widget elementor-widget-restly_pricing_v3\" data-id=\"75627c9\" data-element_type=\"widget\" data-widget_type=\"restly_pricing_v3.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t        <div class=\"restly-pricing-v3-wrapper\">\r\n            <div class=\"pricing-item-seven\">\r\n                <div class=\"pricing-top\">\r\n                    <div class=\"price-top-left\">\r\n                        <h4 class=\"pricing-title\">CUSTOM<\/h4>\r\n                        <span><\/span>\r\n                    <\/div>\r\n                    <span class=\"price\"><\/span>\r\n                <\/div>\r\n                <ul class=\"list-style-three\">\r\n                                        <li class=\"elementor-repeater-item-55cbcba\"><i class=\"bi bi-check-circle\"><\/i>IT Consultations<\/li>\r\n                                        <li class=\"elementor-repeater-item-6b6851f\"><i class=\"bi bi-check-circle\"><\/i>Estimation &amp; Quote<\/li>\r\n                                        <li class=\"elementor-repeater-item-84a187c\"><i class=\"bi bi-check-circle\"><\/i>Contact for More Info<\/li>\r\n                                    <\/ul>\r\n                <a class=\"theme-btn style-six\" href=\"\/contact-us\" target=\"_blank\" rel=\"nofollow\">Contact Us<i class=\"\"><\/i><\/a>            <\/div>\r\n        <\/div>\r\n        \t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t            <\/div>\r\n                        <div class=\"tab-pane fade show \" id=\"pricing-item2-2\" role=\"tabpanel\" aria-labelledby=\"pricing-2-tab2\">\r\n                \t\t<div data-elementor-type=\"section\" data-elementor-id=\"4957\" class=\"elementor elementor-4957\">\r\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9df0c1a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9df0c1a\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f01df88\" data-id=\"f01df88\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e4d906 elementor-widget elementor-widget-restly_pricing_v3\" data-id=\"5e4d906\" data-element_type=\"widget\" data-widget_type=\"restly_pricing_v3.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t        <div class=\"restly-pricing-v3-wrapper\">\r\n            <div class=\"pricing-item-seven\">\r\n                <div class=\"pricing-top\">\r\n                    <div class=\"price-top-left\">\r\n                        <h4 class=\"pricing-title\">Basic<\/h4>\r\n                        <span>Enjoy Yearly ammunites<\/span>\r\n                    <\/div>\r\n                    <span class=\"price\">$25<\/span>\r\n                <\/div>\r\n                <ul class=\"list-style-three\">\r\n                                        <li class=\"elementor-repeater-item-55cbcba\"><i class=\"bi bi-check-circle\"><\/i>Unlimited Reports 100+ Data<\/li>\r\n                                        <li class=\"elementor-repeater-item-6b6851f\"><i class=\"bi bi-check-circle\"><\/i>Connectors<\/li>\r\n                                        <li class=\"elementor-repeater-item-84a187c\"><i class=\"bi bi-check-circle\"><\/i>Yearly Premium Support<\/li>\r\n                                    <\/ul>\r\n                <a class=\"theme-btn style-six\" href=\"\" target=\"_blank\" rel=\"nofollow\">Start Free Trial<i class=\"\"><\/i><\/a>            <\/div>\r\n        <\/div>\r\n        \t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6be8218\" data-id=\"6be8218\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5c067c elementor-widget elementor-widget-restly_pricing_v3\" data-id=\"d5c067c\" data-element_type=\"widget\" data-widget_type=\"restly_pricing_v3.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t        <div class=\"restly-pricing-v3-wrapper\">\r\n            <div class=\"pricing-item-seven\">\r\n                <div class=\"pricing-top\">\r\n                    <div class=\"price-top-left\">\r\n                        <h4 class=\"pricing-title\">Standard<\/h4>\r\n                        <span>Enjoy Yearly ammunites<\/span>\r\n                    <\/div>\r\n                    <span class=\"price\">$35<\/span>\r\n                <\/div>\r\n                <ul class=\"list-style-three\">\r\n                                        <li class=\"elementor-repeater-item-55cbcba\"><i class=\"bi bi-check-circle\"><\/i>Unlimited Reports 100+ Data<\/li>\r\n                                        <li class=\"elementor-repeater-item-6b6851f\"><i class=\"bi bi-check-circle\"><\/i>Connectors<\/li>\r\n                                        <li class=\"elementor-repeater-item-84a187c\"><i class=\"bi bi-check-circle\"><\/i>Yearly Premium Support<\/li>\r\n                                    <\/ul>\r\n                <a class=\"theme-btn style-six\" href=\"\" target=\"_blank\" rel=\"nofollow\">Start Free Trial<i class=\"\"><\/i><\/a>            <\/div>\r\n        <\/div>\r\n        \t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-770d1d9\" data-id=\"770d1d9\" data-element_type=\"column\">\r\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbc64af elementor-widget elementor-widget-restly_pricing_v3\" data-id=\"dbc64af\" data-element_type=\"widget\" data-widget_type=\"restly_pricing_v3.default\">\r\n\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t        <div class=\"restly-pricing-v3-wrapper\">\r\n            <div class=\"pricing-item-seven\">\r\n                <div class=\"pricing-top\">\r\n                    <div class=\"price-top-left\">\r\n                        <h4 class=\"pricing-title\">Premium<\/h4>\r\n                        <span>Enjoy Yearly ammunites<\/span>\r\n                    <\/div>\r\n                    <span class=\"price\">$45<\/span>\r\n                <\/div>\r\n                <ul class=\"list-style-three\">\r\n                                        <li class=\"elementor-repeater-item-55cbcba\"><i class=\"bi bi-check-circle\"><\/i>Unlimited Reports 100+ Data<\/li>\r\n                                        <li class=\"elementor-repeater-item-6b6851f\"><i class=\"bi bi-check-circle\"><\/i>Connectors<\/li>\r\n                                        <li class=\"elementor-repeater-item-84a187c\"><i class=\"bi bi-check-circle\"><\/i>Yearly Premium Support<\/li>\r\n                                    <\/ul>\r\n                <a class=\"theme-btn style-six\" href=\"\" target=\"_blank\" rel=\"nofollow\">Start Free Trial<i class=\"\"><\/i><\/a>            <\/div>\r\n        <\/div>\r\n        \t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t            <\/div>\r\n                        <\/div>\r\n        <\/div>\r\n        \t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/section>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pricing Packages Choose the Right Plan For You Monthly Custom STAND ALONE Enjoy Monthly ammunites 15 Free Server Deployment Unlimited Apps &amp; Schedules Free Six Months Support Contact Us CLOUD SERVICES Enjoy Monthly ammunites 15 No Servers Required Limited Apps &amp; Schedules Free Online Support Contact Us CUSTOM Enjoy Monthly ammunites 15 IT Consultations Estimation [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"blank-template.php","meta":[],"_links":{"self":[{"href":"https:\/\/foresight-lab.com\/en\/wp-json\/wp\/v2\/pages\/5103"}],"collection":[{"href":"https:\/\/foresight-lab.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/foresight-lab.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/foresight-lab.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foresight-lab.com\/en\/wp-json\/wp\/v2\/comments?post=5103"}],"version-history":[{"count":27,"href":"https:\/\/foresight-lab.com\/en\/wp-json\/wp\/v2\/pages\/5103\/revisions"}],"predecessor-version":[{"id":7147,"href":"https:\/\/foresight-lab.com\/en\/wp-json\/wp\/v2\/pages\/5103\/revisions\/7147"}],"wp:attachment":[{"href":"https:\/\/foresight-lab.com\/en\/wp-json\/wp\/v2\/media?parent=5103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}